{"id":529,"count":6,"description":"","link":"https:\/\/www.cucinadelsole.nl\/nl\/tag\/culinaire-reizen\/","name":"culinaire reizen","slug":"culinaire-reizen","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.7.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>culinaire reizen Archives - La Cucina del Sole<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cucinadelsole.nl\/nl\/tag\/culinaire-reizen\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"culinaire reizen Archives - La Cucina del Sole\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cucinadelsole.nl\/nl\/tag\/culinaire-reizen\/\" \/>\n<meta property=\"og:site_name\" content=\"La Cucina del Sole\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:site\" content=\"@LaCucinaDelSole\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.cucinadelsole.nl\/nl\/tag\/culinaire-reizen\/\",\"url\":\"https:\/\/www.cucinadelsole.nl\/nl\/tag\/culinaire-reizen\/\",\"name\":\"culinaire reizen Archives - La Cucina del Sole\",\"isPartOf\":{\"@id\":\"https:\/\/www.cucinadelsole.nl\/nl\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.cucinadelsole.nl\/nl\/tag\/culinaire-reizen\/#breadcrumb\"},\"inLanguage\":\"nl\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.cucinadelsole.nl\/nl\/tag\/culinaire-reizen\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.cucinadelsole.nl\/nl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"culinaire reizen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.cucinadelsole.nl\/nl\/#website\",\"url\":\"https:\/\/www.cucinadelsole.nl\/nl\/\",\"name\":\"La Cucina del Sole\",\"description\":\"Italiaanse kookschool\/Italian cooking school in Amsterdam\",\"publisher\":{\"@id\":\"https:\/\/www.cucinadelsole.nl\/nl\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.cucinadelsole.nl\/nl\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"nl\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.cucinadelsole.nl\/nl\/#organization\",\"name\":\"La Cucina del Sole\",\"url\":\"https:\/\/www.cucinadelsole.nl\/nl\/\",\"sameAs\":[\"http:\/\/nicolettacooks\",\"https:\/\/www.linkedin.com\/in\/nicolettatavella\/\",\"https:\/\/nl.pinterest.com\/lacucinadelsole\/\",\"https:\/\/www.google.com\/url?sa=t&amp;amp;amp;rct=j&amp;amp;amp;q&amp;amp;amp;esrc=s&amp;amp;amp;source=web&amp;amp;amp;cd=11&amp;amp;amp;cad=rja&amp;amp;amp;uact=8&amp;amp;amp;ved=2ahUKEwig9Jqenf3iAhWQh1wKHT4tCzAQFjAKegQIAhAB&amp;amp;amp;url=https:\/\/www.youtube.com\/user\/NicolettaTavella&amp;amp;amp;usg=AOvVaw3Q0pX7Y6WAzDVx4OISYpKH\",\"https:\/\/www.facebook.com\/lacucinadelsole\/\",\"https:\/\/twitter.com\/LaCucinaDelSole\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl\",\"@id\":\"https:\/\/www.cucinadelsole.nl\/nl\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.cucinadelsole.nl\/wp-content\/uploads\/2016\/05\/LOGO-simple-Transparent-JPG-217x300-1.png\",\"contentUrl\":\"https:\/\/www.cucinadelsole.nl\/wp-content\/uploads\/2016\/05\/LOGO-simple-Transparent-JPG-217x300-1.png\",\"width\":217,\"height\":300,\"caption\":\"La Cucina del Sole\"},\"image\":{\"@id\":\"https:\/\/www.cucinadelsole.nl\/nl\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"culinaire reizen Archives - La Cucina del Sole","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cucinadelsole.nl\/nl\/tag\/culinaire-reizen\/","og_locale":"nl_NL","og_type":"article","og_title":"culinaire reizen Archives - La Cucina del Sole","og_url":"https:\/\/www.cucinadelsole.nl\/nl\/tag\/culinaire-reizen\/","og_site_name":"La Cucina del Sole","twitter_card":"summary","twitter_site":"@LaCucinaDelSole","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.cucinadelsole.nl\/nl\/tag\/culinaire-reizen\/","url":"https:\/\/www.cucinadelsole.nl\/nl\/tag\/culinaire-reizen\/","name":"culinaire reizen Archives - La Cucina del Sole","isPartOf":{"@id":"https:\/\/www.cucinadelsole.nl\/nl\/#website"},"breadcrumb":{"@id":"https:\/\/www.cucinadelsole.nl\/nl\/tag\/culinaire-reizen\/#breadcrumb"},"inLanguage":"nl"},{"@type":"BreadcrumbList","@id":"https:\/\/www.cucinadelsole.nl\/nl\/tag\/culinaire-reizen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.cucinadelsole.nl\/nl\/"},{"@type":"ListItem","position":2,"name":"culinaire reizen"}]},{"@type":"WebSite","@id":"https:\/\/www.cucinadelsole.nl\/nl\/#website","url":"https:\/\/www.cucinadelsole.nl\/nl\/","name":"La Cucina del Sole","description":"Italiaanse kookschool\/Italian cooking school in Amsterdam","publisher":{"@id":"https:\/\/www.cucinadelsole.nl\/nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cucinadelsole.nl\/nl\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"nl"},{"@type":"Organization","@id":"https:\/\/www.cucinadelsole.nl\/nl\/#organization","name":"La Cucina del Sole","url":"https:\/\/www.cucinadelsole.nl\/nl\/","sameAs":["http:\/\/nicolettacooks","https:\/\/www.linkedin.com\/in\/nicolettatavella\/","https:\/\/nl.pinterest.com\/lacucinadelsole\/","https:\/\/www.google.com\/url?sa=t&amp;amp;amp;rct=j&amp;amp;amp;q&amp;amp;amp;esrc=s&amp;amp;amp;source=web&amp;amp;amp;cd=11&amp;amp;amp;cad=rja&amp;amp;amp;uact=8&amp;amp;amp;ved=2ahUKEwig9Jqenf3iAhWQh1wKHT4tCzAQFjAKegQIAhAB&amp;amp;amp;url=https:\/\/www.youtube.com\/user\/NicolettaTavella&amp;amp;amp;usg=AOvVaw3Q0pX7Y6WAzDVx4OISYpKH","https:\/\/www.facebook.com\/lacucinadelsole\/","https:\/\/twitter.com\/LaCucinaDelSole"],"logo":{"@type":"ImageObject","inLanguage":"nl","@id":"https:\/\/www.cucinadelsole.nl\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/www.cucinadelsole.nl\/wp-content\/uploads\/2016\/05\/LOGO-simple-Transparent-JPG-217x300-1.png","contentUrl":"https:\/\/www.cucinadelsole.nl\/wp-content\/uploads\/2016\/05\/LOGO-simple-Transparent-JPG-217x300-1.png","width":217,"height":300,"caption":"La Cucina del Sole"},"image":{"@id":"https:\/\/www.cucinadelsole.nl\/nl\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.cucinadelsole.nl\/nl\/wp-json\/wp\/v2\/tags\/529"}],"collection":[{"href":"https:\/\/www.cucinadelsole.nl\/nl\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.cucinadelsole.nl\/nl\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.cucinadelsole.nl\/nl\/wp-json\/wp\/v2\/posts?tags=529"},{"href":"https:\/\/www.cucinadelsole.nl\/nl\/wp-json\/wp\/v2\/ajde_events?tags=529"},{"href":"https:\/\/www.cucinadelsole.nl\/nl\/wp-json\/wp\/v2\/portfolio?tags=529"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}